{"id":51695,"date":"2021-05-22T13:41:10","date_gmt":"2021-05-22T11:41:10","guid":{"rendered":"https:\/\/songfestival.be\/?p=51695"},"modified":"2021-05-22T13:41:11","modified_gmt":"2021-05-22T11:41:11","slug":"hoe-verschillend-stemmen-landen-per-regio-op-songfestival","status":"publish","type":"post","link":"https:\/\/songfestival.be\/en\/analyse\/hoe-verschillend-stemmen-landen-per-regio-op-songfestival\/","title":{"rendered":"How differently do countries vote in Eurovision?"},"content":{"rendered":"<p class=\"post-p-lead\">This article assesses the full rankings of the 2019 Eurovision Grand Final to verify whether or not we denote differences in voting patterns between countries when divided into geographical-based regions.<\/p>\n<p>It thereby uses a classification of the\u00a0<a href=\"https:\/\/unstats.un.org\/unsd\/methodology\/m49\/overview\/\" target=\"_blank\" rel=\"noopener\">United Nations<\/a>. 40 of the 41 participating countries are divided in one of the following five categories: <strong>Asia, East, North, West and South (Europe).<\/strong>\u00a0Because of its deviant geographical position, Australia was not included in the study. We compared detailed jury and televote rankings as available at Eurovision.tv for the 2019 Grand Final, differentiating between the five categories.<\/p>\n<ul>\n<li>Asia: AM, AZ, CY, GE, IL<\/li>\n<li>East: CZ, BY, HU, PL, MD, RO, RU<\/li>\n<li>North: DK, EE, FI, IS, IE, LV, LT, NO, SE, UK<\/li>\n<li>West: AT, BE, CH, DE, FR, NL<\/li>\n<li>South: AL, ES, GR, HR, IT, ME, MK, MT, PT, RS, SI, SM<\/li>\n<\/ul>\n<p>We operationalised the differences in rankings, and thus voting, by calculating the <a href=\"https:\/\/en.wikipedia.org\/wiki\/Standard_deviation\" target=\"_blank\" rel=\"noopener\">standard deviation\u00a0<em>(SD)<\/em><\/a> for each of thee five regions. An SD of 0.0 indicates total consensus and no difference in where a certain song and country were ranked by the five regions. The higher the SD, the more differences we denote.<\/p>\n<p><strong><em>Jury results<\/em><\/strong><\/p>\n<p>The average SD for jury rankings per five regions is <strong>3.3<\/strong>, with peaks for Russia (4.8), Albania (4.9) and Greece (6.3), with near total consensus on Spain (0.8), San Marino (1.1 and Netherlands (1.3). When looking at the top 5 countries of the jury vote based on total rankings, the average SD is 2.7, meaning that there is <strong>more consensus on top countries.\u00a0<\/strong><\/p>\n<p>Interestingly, Asia aside, all regions indicated a song from one of its &#8216;own&#8217; countries as favourite. Also, even though it only came 3rd in the actual jury vote based on points from 1 to 12\u00a0<strong><em>Arcade\u00a0<\/em>actually was the jury favourite<\/strong>\u00a0in average total rankings. Country names are in Dutch in the table underneath, but being the multilingual Eurovision fanatic that you are, you&#8217;ll know which ones they correspond with.<\/p>\n\n<table id=\"tablepress-1376\" class=\"tablepress tablepress-id-1376\">\n<thead>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><th class=\"column-2\">Gemiddelde<\/th><th class=\"column-3\">Azi\u00eb<\/th><th class=\"column-4\">Oost<\/th><th class=\"column-5\">Noord<\/th><th class=\"column-6\">Zuid<\/th><th class=\"column-7\">West<\/th><th class=\"column-8\">SD<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Nederland<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">2<\/td><td class=\"column-4\">4<\/td><td class=\"column-5\">2<\/td><td class=\"column-6\">4<\/td><td class=\"column-7\">1<\/td><td class=\"column-8\">1.3<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Noord-Macedoni\u00eb<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">8<\/td><td class=\"column-4\">1<\/td><td class=\"column-5\">3<\/td><td class=\"column-6\">3<\/td><td class=\"column-7\">5<\/td><td class=\"column-8\">2.6<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Zweden<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">3<\/td><td class=\"column-4\">7<\/td><td class=\"column-5\">1<\/td><td class=\"column-6\">6<\/td><td class=\"column-7\">4<\/td><td class=\"column-8\">2.4<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Azerbeidzjan<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">6<\/td><td class=\"column-4\">2<\/td><td class=\"column-5\">4<\/td><td class=\"column-6\">2<\/td><td class=\"column-7\">9<\/td><td class=\"column-8\">3.0<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Itali\u00eb<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">1<\/td><td class=\"column-4\">8<\/td><td class=\"column-5\">9<\/td><td class=\"column-6\">1<\/td><td class=\"column-7\">2<\/td><td class=\"column-8\">4.0<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Zwitserland<\/td><td class=\"column-2\">6<\/td><td class=\"column-3\">5<\/td><td class=\"column-4\">10<\/td><td class=\"column-5\">6<\/td><td class=\"column-6\">9<\/td><td class=\"column-7\">3<\/td><td class=\"column-8\">2.9<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Tsjechi\u00eb<\/td><td class=\"column-2\">7<\/td><td class=\"column-3\">10<\/td><td class=\"column-4\">3<\/td><td class=\"column-5\">5<\/td><td class=\"column-6\">8<\/td><td class=\"column-7\">8<\/td><td class=\"column-8\">2.8<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Australi\u00eb<\/td><td class=\"column-2\">8<\/td><td class=\"column-3\">13<\/td><td class=\"column-4\">5<\/td><td class=\"column-5\">8<\/td><td class=\"column-6\">5<\/td><td class=\"column-7\">6<\/td><td class=\"column-8\">3.4<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Rusland<\/td><td class=\"column-2\">9<\/td><td class=\"column-3\">7<\/td><td class=\"column-4\">17<\/td><td class=\"column-5\">7<\/td><td class=\"column-6\">7<\/td><td class=\"column-7\">14<\/td><td class=\"column-8\">4.8<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Malta<\/td><td class=\"column-2\">10<\/td><td class=\"column-3\">4<\/td><td class=\"column-4\">5<\/td><td class=\"column-5\">14<\/td><td class=\"column-6\">11<\/td><td class=\"column-7\">11<\/td><td class=\"column-8\">4.3<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Frankrijk<\/td><td class=\"column-2\">11<\/td><td class=\"column-3\">12<\/td><td class=\"column-4\">11<\/td><td class=\"column-5\">13<\/td><td class=\"column-6\">13<\/td><td class=\"column-7\">7<\/td><td class=\"column-8\">2.5<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Cyprus<\/td><td class=\"column-2\">12<\/td><td class=\"column-3\">9<\/td><td class=\"column-4\">14<\/td><td class=\"column-5\">20<\/td><td class=\"column-6\">10<\/td><td class=\"column-7\">12<\/td><td class=\"column-8\">4.6<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Denemarken<\/td><td class=\"column-2\">13<\/td><td class=\"column-3\">18<\/td><td class=\"column-4\">8<\/td><td class=\"column-5\">11<\/td><td class=\"column-6\">15<\/td><td class=\"column-7\">10<\/td><td class=\"column-8\">4.0<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Noorwegen<\/td><td class=\"column-2\">14<\/td><td class=\"column-3\">20<\/td><td class=\"column-4\">14<\/td><td class=\"column-5\">10<\/td><td class=\"column-6\">19<\/td><td class=\"column-7\">13<\/td><td class=\"column-8\">4.2<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Servi\u00eb<\/td><td class=\"column-2\">15<\/td><td class=\"column-3\">22<\/td><td class=\"column-4\">12<\/td><td class=\"column-5\">14<\/td><td class=\"column-6\">17<\/td><td class=\"column-7\">18<\/td><td class=\"column-8\">3.8<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">Sloveni\u00eb<\/td><td class=\"column-2\">16<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">14<\/td><td class=\"column-5\">18<\/td><td class=\"column-6\">14<\/td><td class=\"column-7\">20<\/td><td class=\"column-8\">2.8<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">IJsland<\/td><td class=\"column-2\">17<\/td><td class=\"column-3\">21<\/td><td class=\"column-4\">13<\/td><td class=\"column-5\">17<\/td><td class=\"column-6\">20<\/td><td class=\"column-7\">15<\/td><td class=\"column-8\">3.3<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">Estland<\/td><td class=\"column-2\">18<\/td><td class=\"column-3\">19<\/td><td class=\"column-4\">19<\/td><td class=\"column-5\">12<\/td><td class=\"column-6\">18<\/td><td class=\"column-7\">22<\/td><td class=\"column-8\">3.7<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">Wit-Rusland<\/td><td class=\"column-2\">19<\/td><td class=\"column-3\">15<\/td><td class=\"column-4\">18<\/td><td class=\"column-5\">22<\/td><td class=\"column-6\">20<\/td><td class=\"column-7\">17<\/td><td class=\"column-8\">2.7<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">Duitsland<\/td><td class=\"column-2\">20<\/td><td class=\"column-3\">25<\/td><td class=\"column-4\">23<\/td><td class=\"column-5\">16<\/td><td class=\"column-6\">22<\/td><td class=\"column-7\">16<\/td><td class=\"column-8\">4.2<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">Verenigd Koninkrijk<\/td><td class=\"column-2\">21<\/td><td class=\"column-3\">16<\/td><td class=\"column-4\">21<\/td><td class=\"column-5\">19<\/td><td class=\"column-6\">25<\/td><td class=\"column-7\">19<\/td><td class=\"column-8\">3.3<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">Albani\u00eb<\/td><td class=\"column-2\">22<\/td><td class=\"column-3\">17<\/td><td class=\"column-4\">21<\/td><td class=\"column-5\">25<\/td><td class=\"column-6\">12<\/td><td class=\"column-7\">21<\/td><td class=\"column-8\">4.9<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">Griekenland<\/td><td class=\"column-2\">23<\/td><td class=\"column-3\">11<\/td><td class=\"column-4\">20<\/td><td class=\"column-5\">26<\/td><td class=\"column-6\">16<\/td><td class=\"column-7\">25<\/td><td class=\"column-8\">6.3<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">Isra\u00ebl<\/td><td class=\"column-2\">24<\/td><td class=\"column-3\">26<\/td><td class=\"column-4\">24<\/td><td class=\"column-5\">21<\/td><td class=\"column-6\">22<\/td><td class=\"column-7\">23<\/td><td class=\"column-8\">1.9<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">Spanje<\/td><td class=\"column-2\">25<\/td><td class=\"column-3\">23<\/td><td class=\"column-4\">25<\/td><td class=\"column-5\">23<\/td><td class=\"column-6\">24<\/td><td class=\"column-7\">24<\/td><td class=\"column-8\">0.8<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">San Marino<\/td><td class=\"column-2\">26<\/td><td class=\"column-3\">24<\/td><td class=\"column-4\">26<\/td><td class=\"column-5\">24<\/td><td class=\"column-6\">26<\/td><td class=\"column-7\">26<\/td><td class=\"column-8\">1.1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1376 from cache -->\n<p><em><strong>Televote results<\/strong><\/em><\/p>\n<p>The average SD for televote rankings is 3.4, nearly identical to the jury SD. This means that there is hardly any difference in how diverse juries and audiences voted in the 2019 final. There was <strong>a near total consensus on the second place for the Netherlands<\/strong> (SD = 0.5), with bigger differences for all other countries in the top 5. Nonetheless, with an average SD of 2.1 for the top five countries according to the televote rankings, we also see considerably more consensus here for the highest rated songs. The main differences were spotted per region for Albania (6.6), Israel (5.4) and Serbia and Cyprus (both 4.9).<\/p>\n\n<table id=\"tablepress-1378\" class=\"tablepress tablepress-id-1378\">\n<thead>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><th class=\"column-2\">Gemiddelde<\/th><th class=\"column-3\">Azi\u00eb<\/th><th class=\"column-4\">Oost<\/th><th class=\"column-5\">Noord<\/th><th class=\"column-6\">Zuid<\/th><th class=\"column-7\">West<\/th><th class=\"column-8\">SD<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Noorwegen<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">5<\/td><td class=\"column-4\">2<\/td><td class=\"column-5\">1<\/td><td class=\"column-6\">5<\/td><td class=\"column-7\">1<\/td><td class=\"column-8\">2.0<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Nederland<\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">3<\/td><td class=\"column-4\">2<\/td><td class=\"column-5\">3<\/td><td class=\"column-6\">2<\/td><td class=\"column-7\">3<\/td><td class=\"column-8\">0.5<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Itali\u00eb<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">2<\/td><td class=\"column-4\">7<\/td><td class=\"column-5\">8<\/td><td class=\"column-6\">1<\/td><td class=\"column-7\">1<\/td><td class=\"column-8\">3.4<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Zwitserland<\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">4<\/td><td class=\"column-4\">6<\/td><td class=\"column-5\">6<\/td><td class=\"column-6\">4<\/td><td class=\"column-7\">4<\/td><td class=\"column-8\">1.1<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Rusland<\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">1<\/td><td class=\"column-4\">1<\/td><td class=\"column-5\">9<\/td><td class=\"column-6\">3<\/td><td class=\"column-7\">6<\/td><td class=\"column-8\">3.5<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Ijsland<\/td><td class=\"column-2\">6<\/td><td class=\"column-3\">9<\/td><td class=\"column-4\">4<\/td><td class=\"column-5\">2<\/td><td class=\"column-6\">7<\/td><td class=\"column-7\">7<\/td><td class=\"column-8\">2.8<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Australi\u00eb<\/td><td class=\"column-2\">7<\/td><td class=\"column-3\">7<\/td><td class=\"column-4\">8<\/td><td class=\"column-5\">5<\/td><td class=\"column-6\">8<\/td><td class=\"column-7\">5<\/td><td class=\"column-8\">1.5<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Azerbeidzjan<\/td><td class=\"column-2\">8<\/td><td class=\"column-3\">12<\/td><td class=\"column-4\">5<\/td><td class=\"column-5\">11<\/td><td class=\"column-6\">9<\/td><td class=\"column-7\">12<\/td><td class=\"column-8\">2.9<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Zweden<\/td><td class=\"column-2\">9<\/td><td class=\"column-3\">11<\/td><td class=\"column-4\">14<\/td><td class=\"column-5\">4<\/td><td class=\"column-6\">13<\/td><td class=\"column-7\">10<\/td><td class=\"column-8\">3.9<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Spanje<\/td><td class=\"column-2\">10<\/td><td class=\"column-3\">8<\/td><td class=\"column-4\">18<\/td><td class=\"column-5\">12<\/td><td class=\"column-6\">10<\/td><td class=\"column-7\">8<\/td><td class=\"column-8\">4.1<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">Denemarken<\/td><td class=\"column-2\">11<\/td><td class=\"column-3\">20<\/td><td class=\"column-4\">17<\/td><td class=\"column-5\">10<\/td><td class=\"column-6\">16<\/td><td class=\"column-7\">9<\/td><td class=\"column-8\">4.7<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">Estland<\/td><td class=\"column-2\">12<\/td><td class=\"column-3\">18<\/td><td class=\"column-4\">15<\/td><td class=\"column-5\">7<\/td><td class=\"column-6\">19<\/td><td class=\"column-7\">17<\/td><td class=\"column-8\">4.8<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">Noord-Macedoni\u00eb<\/td><td class=\"column-2\">13<\/td><td class=\"column-3\">13<\/td><td class=\"column-4\">12<\/td><td class=\"column-5\">17<\/td><td class=\"column-6\">6<\/td><td class=\"column-7\">16<\/td><td class=\"column-8\">4.3<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">Frankrijk<\/td><td class=\"column-2\">13<\/td><td class=\"column-3\">6<\/td><td class=\"column-4\">11<\/td><td class=\"column-5\">13<\/td><td class=\"column-6\">17<\/td><td class=\"column-7\">11<\/td><td class=\"column-8\">4.0<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">Sloveni\u00eb<\/td><td class=\"column-2\">15<\/td><td class=\"column-3\">19<\/td><td class=\"column-4\">9<\/td><td class=\"column-5\">15<\/td><td class=\"column-6\">14<\/td><td class=\"column-7\">14<\/td><td class=\"column-8\">3.6<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">San Marino<\/td><td class=\"column-2\">16<\/td><td class=\"column-3\">16<\/td><td class=\"column-4\">13<\/td><td class=\"column-5\">18<\/td><td class=\"column-6\">15<\/td><td class=\"column-7\">23<\/td><td class=\"column-8\">3.8<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">Tsjechi\u00eb<\/td><td class=\"column-2\">17<\/td><td class=\"column-3\">20<\/td><td class=\"column-4\">16<\/td><td class=\"column-5\">14<\/td><td class=\"column-6\">21<\/td><td class=\"column-7\">19<\/td><td class=\"column-8\">2.9<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">Servi\u00eb<\/td><td class=\"column-2\">18<\/td><td class=\"column-3\">23<\/td><td class=\"column-4\">18<\/td><td class=\"column-5\">23<\/td><td class=\"column-6\">12<\/td><td class=\"column-7\">15<\/td><td class=\"column-8\">4.9<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">Malta<\/td><td class=\"column-2\">19<\/td><td class=\"column-3\">14<\/td><td class=\"column-4\">21<\/td><td class=\"column-5\">16<\/td><td class=\"column-6\">20<\/td><td class=\"column-7\">21<\/td><td class=\"column-8\">3.2<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">Cyprus<\/td><td class=\"column-2\">20<\/td><td class=\"column-3\">10<\/td><td class=\"column-4\">22<\/td><td class=\"column-5\">19<\/td><td class=\"column-6\">18<\/td><td class=\"column-7\">22<\/td><td class=\"column-8\">4.9<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">Isra\u00ebl<\/td><td class=\"column-2\">21<\/td><td class=\"column-3\">15<\/td><td class=\"column-4\">9<\/td><td class=\"column-5\">22<\/td><td class=\"column-6\">22<\/td><td class=\"column-7\">18<\/td><td class=\"column-8\">5.4<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">Albani\u00eb<\/td><td class=\"column-2\">22<\/td><td class=\"column-3\">24<\/td><td class=\"column-4\">24<\/td><td class=\"column-5\">24<\/td><td class=\"column-6\">11<\/td><td class=\"column-7\">13<\/td><td class=\"column-8\">6.6<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">Wit-Rusland<\/td><td class=\"column-2\">23<\/td><td class=\"column-3\">17<\/td><td class=\"column-4\">20<\/td><td class=\"column-5\">20<\/td><td class=\"column-6\">23<\/td><td class=\"column-7\">26<\/td><td class=\"column-8\">3.4<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">Griekenland<\/td><td class=\"column-2\">24<\/td><td class=\"column-3\">22<\/td><td class=\"column-4\">23<\/td><td class=\"column-5\">25<\/td><td class=\"column-6\">24<\/td><td class=\"column-7\">24<\/td><td class=\"column-8\">1.1<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">Duitsland<\/td><td class=\"column-2\">25<\/td><td class=\"column-3\">25<\/td><td class=\"column-4\">25<\/td><td class=\"column-5\">26<\/td><td class=\"column-6\">25<\/td><td class=\"column-7\">20<\/td><td class=\"column-8\">2.3<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">Verenigd Koninkrijk<\/td><td class=\"column-2\">26<\/td><td class=\"column-3\">26<\/td><td class=\"column-4\">26<\/td><td class=\"column-5\">21<\/td><td class=\"column-6\">26<\/td><td class=\"column-7\">25<\/td><td class=\"column-8\">2.2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1378 from cache -->\n<p><strong><em>Conclusions<\/em><\/strong><\/p>\n<p>When further grouping countries together into <strong>three bigger regional groups<\/strong> (Asia and Eastern Europe \/ Northern and Western Europe and Southern Europe still as an individual region), the average SD&#8217;s are much lower, although the differences in taste and voting patterns between juries (average SD = 1.7) and audiences (2.1) from different regions are slightly more outspoken.<\/p>\n<p>Summarising the above, there are no very wide differences in how people from geographically similar countries rank songs. Particularly for the highest ranked songs, there is often broad consensus about which songs are perceived as best. And this is just applicable for the 2019 Grand Final, which saw very spread out results across the board. For the 2017 results, in which Salvador Sobral swept both votes, the SD would probably be marginal. Thus, small taste and voting differences aside, there is <strong>a considerable amount of consensus between both jury and audience voters from all participating Eurovision nations.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>We nemen de resultaten van 2019 onder de loep.<\/p>\n","protected":false},"author":5,"featured_media":51710,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2674],"tags":[1280,4862,4583,2807,2113,254,4920,5468,4978,3400,5580,219,17,4925,4926,1897,5579,970,54,1758,4182,1493,5898,2020,5535,19,4848,5452,4953,1759,1760,2021],"class_list":["post-51695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyse","tag-analyse","tag-audience","tag-duncan-laurence","tag-esc","tag-esf","tag-eurosong","tag-eurosong-2020","tag-eurosong-2021","tag-eurosong-rotterdam","tag-eurosongfestival","tag-eurosongfestival-2021","tag-eurovisiesongfestival","tag-eurovision","tag-gastland-songfestival","tag-gaststad-songfestival","tag-holland","tag-hooverphonic-2021","tag-jury","tag-nederland","tag-points","tag-professional-jury","tag-punten","tag-puntenteelling","tag-results","tag-rotterdam-2021","tag-songfestival","tag-songfestival-2020","tag-songfestival-2021","tag-songfestival-rotterdam","tag-televoting","tag-vakjury","tag-votes"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"en","enabled_languages":["nl","fr","en"],"languages":{"nl":{"title":true,"content":true,"excerpt":true},"fr":{"title":false,"content":false,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/posts\/51695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/comments?post=51695"}],"version-history":[{"count":0,"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/posts\/51695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/media\/51710"}],"wp:attachment":[{"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/media?parent=51695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/categories?post=51695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/songfestival.be\/en\/wp-json\/wp\/v2\/tags?post=51695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}