{"id":11148,"date":"2016-10-14T13:33:11","date_gmt":"2016-10-14T11:33:11","guid":{"rendered":"https:\/\/songfestival.be\/?post_type=releases&#038;p=11148"},"modified":"2016-10-17T11:06:49","modified_gmt":"2016-10-17T09:06:49","slug":"eurosong-deelnemer-adil-brengt-nieuwe-single-repeat-uit","status":"publish","type":"post","link":"https:\/\/songfestival.be\/fr\/eurosong2016\/eurosong-deelnemer-adil-brengt-nieuwe-single-repeat-uit\/","title":{"rendered":"\u00ab\u00a0Eurosong\u00a0\u00bb-participant Adil apporte un nouveau single \u00ab\u00a0Repeat\u00a0\u00bb de"},"content":{"rendered":"<p style=\"color: #D49D6E; font-weight: bold;\" class=\"post-p-lead\">* Traduit automatiquement *<\/p>\n<div id=\"fb-root\"><\/div>\n<p class=\"lead\">Adil A, un des candidats cette ann\u00e9e \u00e0 <em>eurosong 2016<\/em>, n\u2019est pas silencieux. Avec la <em>r\u00e9p\u00e9tition (que l\u2019\u00e9t\u00e9)<\/em> , il apporte un nouveau num\u00e9ro. Il y a m\u00eame un E.P. pour sortir le jeune homme\u00a0!<\/p>\n<p>Autour de Amaryllis Uitterlinden, Astrid et Tom Frantzis \u00e9tait assez calme apr\u00e8s leur participation \u00e0 la chaleur flamande pour le concours Eurovision de la chanson en 2016. Adil est continuer \u00e0 lib\u00e9rer la musique. Apr\u00e8s son entr\u00e9e <em>Eurovision<\/em><strong> <em>Dans notre Nature<\/em> <\/strong> et Sony Music sort seule <em>Prenez moi avec vous<\/em> , il est maintenant temps pour <em>r\u00e9p\u00e9ter<\/em>, une ode \u00e0 l\u2019\u00e9t\u00e9 dernier.<\/p>\n<p>Adil\u00a0: je suis extr\u00eamement content de mon nouveau single. La chanson arrive au bon moment. Apr\u00e8s un long \u00e9t\u00e9, qui devrait prendre un peu plus. <em>\u00ab\u00a0Je ne peux pas l\u00e2cher qu\u2019\u00e9t\u00e9 envelopp\u00e9 en or.\u00a0\u00bb<\/em> -qui parle de lui-m\u00eame. Donc tout le monde a la chaleur de l\u2019\u00e9t\u00e9 encore un peu dans la voiture, le bus, le train&#8230; aussi si elle sera vraiment froid.\u00a0\u00bb<\/p>\n<p>Apr\u00e8s <em>eurosong<\/em> tir\u00e9 Adil \u00e0 <strong>Londres<\/strong> pour travailler sur nouvelles chansons. Dans le studio de musique, il a travaill\u00e9 dur sur sa voix et pr\u00e9pare le nouveau num\u00e9ro <em>r\u00e9p\u00e9ter<\/em> pour. Encore plus de nouveaux travaux bient\u00f4t nous attendons de lui, parce qu\u2019il vient un<strong> E.P.<\/strong> d\u2019Emily<\/p>\n<p>Vous pouvez t\u00e9l\u00e9charger via <a href=\"https:\/\/itunes.apple.com\/nl\/album\/repeat-single\/id1163886712\">iTunes <\/a>ou <em>r\u00e9p\u00e9ter<\/em> des flux par le biais, par exemple, <a href=\"http:\/\/www.deezer.com\/album\/14270168?utm_source=deezer&#038;utm_content=album-14270168&#038;utm_term=636324551_1476323720&#038;utm_medium=web\" target=\"_blank\">Deezer<\/a>. Adil a \u00e9galement pris un clip vid\u00e9o pour son nouveau single.<\/p>\n<div class=\"fitvids-video\">\n<div class=\"container-lazyload preview-lazyload container-youtube js-lazyload--not-loaded\"><a class=\"lazy-load-youtube preview-lazyload preview-youtube\" href=\"https:\/\/www.youtube.com\/watch?v=7z0G5RIZAEQ\" video-title=\"Adil - Repeat- Official video\" title=\"Play Video &quot;Adil - Repeat- Official video&quot;\" style=\"text-decoration:none;color:#000\">https:\/\/www.youtube.com\/watch?v=7z0G5RIZAEQ<\/a> <noscript>Vid\u00e9o ne peut pas \u00eatre charg\u00e9\u00a0: Adil \u2013 r\u00e9p\u00e9tition-Official video (https:\/\/www.youtube.com\/watch?v=7z0G5RIZAEQ)<\/noscript><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nous pr\u00e9voyons bient\u00f4t la nouvelle \u0153uvre de lui encore plus, parce qu\u2019il vient un E.P. d\u2019Emily<\/p>\n","protected":false},"author":4,"featured_media":3082,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[871,769,2437,2043,254,1157,783,96,2436,2438,40,19,1968],"class_list":["post-11148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eurosong2016","tag-adil","tag-adil-aarab","tag-adil-music","tag-e-p","tag-eurosong","tag-in-our-nature","tag-laura-tesoro","tag-londen","tag-repeat","tag-repeat-that-summer","tag-single","tag-songfestival","tag-take-me-with-you"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"fr","enabled_languages":["nl","fr","en"],"languages":{"nl":{"title":true,"content":true,"excerpt":true},"fr":{"title":true,"content":true,"excerpt":true},"en":{"title":true,"content":true,"excerpt":true}}},"_links":{"self":[{"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/posts\/11148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/comments?post=11148"}],"version-history":[{"count":0,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/posts\/11148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/media\/3082"}],"wp:attachment":[{"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/media?parent=11148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/categories?post=11148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/tags?post=11148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}