{"id":36224,"date":"2019-05-09T14:51:21","date_gmt":"2019-05-09T12:51:21","guid":{"rendered":"https:\/\/songfestival.be\/?p=36224"},"modified":"2019-05-09T09:06:43","modified_gmt":"2019-05-09T07:06:43","slug":"ontdek-wake-up-in-gebarentaal","status":"publish","type":"post","link":"https:\/\/songfestival.be\/fr\/landen\/be\/ontdek-wake-up-in-gebarentaal\/","title":{"rendered":"Ontdek &lsquo;Wake Up&rsquo; in gebarentaal"},"content":{"rendered":"<p class=\"post-p-lead\">Een vertaling in gebarentaal van de Belgische inzending, de Nederlandse omroep heeft daarvoor gezorgd. AVROTROS wil hiermee doven en slechthorenden de kans geven om ook ten volle te kunnen genieten van het komende Songfestival.<\/p>\n<p>De inzendingen van Nederland zelf, IJsland, Griekenland, Cyprus \u00e9n Belgi\u00eb hebben elk hun vertaling in gebarentaal gekregen. Zo ziet dat er uit voor het lied van Eliot:<\/p>\n<div class=\"youtube\" data-embed=\"NZqWKnoNvls\" data-time=\"0\">\n<div class=\"play-button\">\n<img decoding=\"async\" class=\"play-button\" alt=\"play\" src=\"https:\/\/songfestival.be\/wp-content\/themes\/songfestival\/img\/play.svg\" \/>\n<\/div>\n<\/div>\n<p>Er komen nog video&rsquo;s online op de <a href=\"https:\/\/www.youtube.com\/user\/avro\/search?query=gebarentaal\" target=\"_blank\" rel=\"noopener\">YouTube-pagina<\/a> van de omroep van Nederland. Het is niet de eerste keer dat de Nederlanders uitpakken met de liedjes in gebarentaal. Vorig jaar was dat bijvoorbeeld ook het geval.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Er komen heel wat handbewegingen aan te pas. <\/p>\n","protected":false},"author":4,"featured_media":36225,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[329,4355],"tags":[4356,2807,2113,254,219,17,229,19,4213],"class_list":["post-36224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-be","category-tel-aviv-2019","tag-4356","tag-esc","tag-esf","tag-eurosong","tag-eurovisiesongfestival","tag-eurovision","tag-israel","tag-songfestival","tag-tel-aviv"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["nl","fr","en"],"languages":{"nl":{"title":true,"content":true,"excerpt":true},"fr":{"title":false,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/posts\/36224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/comments?post=36224"}],"version-history":[{"count":0,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/posts\/36224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/media\/36225"}],"wp:attachment":[{"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/media?parent=36224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/categories?post=36224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/songfestival.be\/fr\/wp-json\/wp\/v2\/tags?post=36224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}